{"id":238191,"date":"2026-03-28T21:43:01","date_gmt":"2026-03-28T20:43:01","guid":{"rendered":"https:\/\/labellavitarealestate.com\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/"},"modified":"2026-03-28T21:43:01","modified_gmt":"2026-03-28T20:43:01","slug":"n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia","status":"publish","type":"property","link":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/","title":{"rendered":"Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":238193,"parent":0,"menu_order":0,"template":"","property_type":[1881,1981,2475],"property_status":[],"property_feature":[2928,2868,1862,1868,2821,3452,1865,3583,2827,1869,1874,2057,2392],"property_label":[1870],"property_city":[3596],"property_area":[2054,3597],"class_list":["post-238191","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-apartamentos","property_type-aticos","property_type-bungalows-es","property_feature-acristalamiento-climalit","property_feature-aerotermia-es","property_feature-aire-acondicionado","property_feature-aparcamiento","property_feature-cocina-amueblada","property_feature-exterior","property_feature-jardin","property_feature-paneles-solares","property_feature-puerta-de-seguridad","property_feature-solarium-es","property_feature-terraza","property_feature-trastero","property_feature-video-intercom-es","property_label-obra-nueva","property_city-fuente-alamo","property_area-costa-calida","property_area-costa-calida-interior"],"property_meta":{"_alp_processed":["1775025996"],"_last_translation_edit_mode":["translation-editor"],"fave_property_price":["169119"],"fave_property_size":["70"],"fave_property_land":["117"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["2"],"fave_property_garage":["1"],"fave_property_id":["N8616"],"fave_property_map":["1"],"fave_property_images":["235968","235969","235970","235971","235972","235973","235974","235975","235976","235977","235978","235979","235980","235981","235982"],"fave_agent_display_option":["agent_info"],"fave_agents":["9878"],"fave_energy_class":["B"],"redsp_ref":["N8616"],"_wp_page_template":["default"],"fave_property_map_address":["La Pinilla, Fuente \u00c1lamo, Murcia, Espa\u00f1a"],"fave_property_address":["Fuente \u00c1lamo, Murcia, Espa\u00f1a"],"_thumbnail_id":["238193"],"_wpml_word_count":["14"],"houzez_total_property_views":["44"],"houzez_views_by_date":["a:20:{s:10:\"04-01-2026\";i:6;s:10:\"04-02-2026\";i:2;s:10:\"04-04-2026\";i:1;s:10:\"04-05-2026\";i:3;s:10:\"04-06-2026\";i:5;s:10:\"04-08-2026\";i:1;s:10:\"04-12-2026\";i:1;s:10:\"04-13-2026\";i:1;s:10:\"04-15-2026\";i:1;s:10:\"04-16-2026\";i:3;s:10:\"04-19-2026\";i:4;s:10:\"04-21-2026\";i:2;s:10:\"04-22-2026\";i:1;s:10:\"04-26-2026\";i:1;s:10:\"04-28-2026\";i:4;s:10:\"05-01-2026\";i:1;s:10:\"05-03-2026\";i:1;s:10:\"05-06-2026\";i:2;s:10:\"05-10-2026\";i:3;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 15:23:31"],"fave_property_year":["7\/2027"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"additional_features":["a:8:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:10:\"\ud83c\udfd6 Beach\";s:29:\"fave_additional_feature_value\";s:5:\"15 km\";}i:1;a:1:{s:29:\"fave_additional_feature_title\";s:26:\"\ud83c\udf7d\ufe0f Bars & Restaurants\";}i:2;a:1:{s:29:\"fave_additional_feature_title\";s:16:\"\ud83d\uded2 Supermarket\";}i:3;a:1:{s:29:\"fave_additional_feature_title\";s:20:\"\ud83d\udecd Shopping Centre\";}i:4;a:1:{s:29:\"fave_additional_feature_title\";s:15:\"\u26f3 Golf Course\";}i:5;a:1:{s:29:\"fave_additional_feature_title\";s:12:\"\ud83c\udfeb Schools\";}i:6;a:1:{s:29:\"fave_additional_feature_title\";s:13:\"\ud83c\udfe5 Hospital\";}i:7;a:1:{s:29:\"fave_additional_feature_title\";s:14:\"\u2708\ufe0f Airport\";}}"],"floor_plans":["a:1:{i:0;a:2:{s:15:\"fave_plan_title\";s:27:\"Ground Floor Apartment Plan\";s:15:\"fave_plan_image\";s:109:\"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA-7.jpg\";}}"],"litespeed_vpi_list":["a:4:{i:0;s:31:\"la-bella-vita-logotype-text.png\";i:1;s:34:\"Borislav-La-Bella-Vita-150x150.jpg\";i:2;s:27:\"La-Bella-Vita-Logo-Left.svg\";i:3;s:46:\"NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\";}"],"_elementor_page_assets":["a:0:{}"],"_elementor_global_class_usage_indexed":["1"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705<\/title>\n<meta name=\"description\" content=\"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705\" \/>\n<meta property=\"og:description\" content=\"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BELLA VITA Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/labellavitarealestate\" \/>\n<meta property=\"og:image\" content=\"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LBV_Real_Estate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/\"},\"author\":{\"name\":\"Diana Tsybulina\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#\\\/schema\\\/person\\\/681224c7252cd962ee224588e6c07d18\"},\"headline\":\"Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia\",\"datePublished\":\"2026-03-28T20:43:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/\",\"name\":\"\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\",\"datePublished\":\"2026-03-28T20:43:01+00:00\",\"description\":\"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\",\"contentUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"in La Pinilla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/\",\"name\":\"LA BELLA VITA Real Estate in Costa Blanca, Spain\",\"description\":\"Properties for sale in Costa Blanca\",\"publisher\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#organization\"},\"alternateName\":\"LA BELLA VITA Real Estate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#organization\",\"name\":\"LA BELLA VITA Real Estate in Costa Blanca\",\"alternateName\":\"LA BELLA VITA\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la-bella-vita-logotype-gold.svg\",\"contentUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la-bella-vita-logotype-gold.svg\",\"width\":366,\"height\":71,\"caption\":\"LA BELLA VITA Real Estate in Costa Blanca\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/labellavitarealestate\",\"https:\\\/\\\/x.com\\\/LBV_Real_Estate\",\"https:\\\/\\\/www.instagram.com\\\/labellavita_real_estate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/labellavitarealestate\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/labellavitarealestate\\\/_saved\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCP6t8aNDgIarJyJYgFZ4XTA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/#\\\/schema\\\/person\\\/681224c7252cd962ee224588e6c07d18\",\"name\":\"Diana Tsybulina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"caption\":\"Diana Tsybulina\"},\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/es\\\/author\\\/diana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705","description":"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/","og_locale":"es_ES","og_type":"article","og_title":"\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705","og_description":"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms","og_url":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/","og_site_name":"LA BELLA VITA Real Estate","article_publisher":"https:\/\/www.facebook.com\/labellavitarealestate","og_image":[{"width":1920,"height":1080,"url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@LBV_Real_Estate","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#article","isPartOf":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/"},"author":{"name":"Diana Tsybulina","@id":"https:\/\/labellavitarealestate.com\/es\/#\/schema\/person\/681224c7252cd962ee224588e6c07d18"},"headline":"Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia","datePublished":"2026-03-28T20:43:01+00:00","mainEntityOfPage":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/"},"wordCount":14,"publisher":{"@id":"https:\/\/labellavitarealestate.com\/es\/#organization"},"image":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#primaryimage"},"thumbnailUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/","url":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/","name":"\u27a1\ufe0f Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia \u2705","isPartOf":{"@id":"https:\/\/labellavitarealestate.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#primaryimage"},"image":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#primaryimage"},"thumbnailUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg","datePublished":"2026-03-28T20:43:01+00:00","description":"Ref. N8616 | \u20ac169119 Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia | 70 m\u00b2 | 117 m\u00b2 plot | 2 bedrooms","breadcrumb":{"@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#primaryimage","url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg","contentUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2026\/03\/NEW-BUILD-BUNGALOWS-IN-FUENTE-ALAMO-MURCIA.jpg","width":1920,"height":1080,"caption":"in La Pinilla"},{"@type":"BreadcrumbList","@id":"https:\/\/labellavitarealestate.com\/es\/property\/n8616-new-build-apartments-for-sale-in-fuente-alamo-murcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/labellavitarealestate.com\/es\/"},{"@type":"ListItem","position":2,"name":"Propiedades","item":"https:\/\/labellavitarealestate.com\/es\/property\/"},{"@type":"ListItem","position":3,"name":"Nuevos apartamentos en venta en la planta baja y \u00faltima en Fuente \u00c1lamo, Murcia"}]},{"@type":"WebSite","@id":"https:\/\/labellavitarealestate.com\/es\/#website","url":"https:\/\/labellavitarealestate.com\/es\/","name":"LA BELLA VITA Real Estate in Costa Blanca, Spain","description":"Properties for sale in Costa Blanca","publisher":{"@id":"https:\/\/labellavitarealestate.com\/es\/#organization"},"alternateName":"LA BELLA VITA Real Estate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labellavitarealestate.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/labellavitarealestate.com\/es\/#organization","name":"LA BELLA VITA Real Estate in Costa Blanca","alternateName":"LA BELLA VITA","url":"https:\/\/labellavitarealestate.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/labellavitarealestate.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2021\/12\/la-bella-vita-logotype-gold.svg","contentUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2021\/12\/la-bella-vita-logotype-gold.svg","width":366,"height":71,"caption":"LA BELLA VITA Real Estate in Costa Blanca"},"image":{"@id":"https:\/\/labellavitarealestate.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/labellavitarealestate","https:\/\/x.com\/LBV_Real_Estate","https:\/\/www.instagram.com\/labellavita_real_estate\/","https:\/\/www.linkedin.com\/in\/labellavitarealestate\/","https:\/\/www.pinterest.es\/labellavitarealestate\/_saved\/","https:\/\/www.youtube.com\/channel\/UCP6t8aNDgIarJyJYgFZ4XTA"]},{"@type":"Person","@id":"https:\/\/labellavitarealestate.com\/es\/#\/schema\/person\/681224c7252cd962ee224588e6c07d18","name":"Diana Tsybulina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","caption":"Diana Tsybulina"},"url":"https:\/\/labellavitarealestate.com\/es\/author\/diana\/"}]}},"_links":{"self":[{"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/properties\/238191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/properties\/238191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/media\/238193"}],"wp:attachment":[{"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/media?parent=238191"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_type?post=238191"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_status?post=238191"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_feature?post=238191"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_label?post=238191"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_city?post=238191"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/es\/wp-json\/wp\/v2\/property_area?post=238191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}