{"id":174843,"date":"2025-08-27T15:33:58","date_gmt":"2025-08-27T14:33:58","guid":{"rendered":"https:\/\/labellavitarealestate.com\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/"},"modified":"2025-08-27T15:49:42","modified_gmt":"2025-08-27T14:49:42","slug":"in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland","status":"publish","type":"property","link":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/","title":{"rendered":"Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":174735,"parent":0,"menu_order":0,"template":"","property_type":[1984,2373,2071],"property_status":[],"property_feature":[2862,1933,2907,2940,2852,3243,2889,2815,2068,2959,2066,3290,3324,2167,2065,2063,2829,2416,2165,2932],"property_label":[2169],"property_city":[3322,3187,3323],"property_area":[1914,2194],"class_list":["post-174843","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-huizen","property_type-percelen","property_type-villas-nl","property_feature-aerothermie","property_feature-buitendouche","property_feature-climalit-beglazing","property_feature-domotica","property_feature-elektrische-rolluiken","property_feature-gelijkvloers","property_feature-hoek-perceel","property_feature-ingerichte-keuken","property_feature-opslag","property_feature-optionele-kelder","property_feature-parkeerplaats","property_feature-privezwembad","property_feature-rustiek-land","property_feature-solarium-nl","property_feature-terras","property_feature-tuin","property_feature-veiligheidsdeur","property_feature-video-intercom-nl","property_feature-vloerverwarming","property_feature-vooraf-geinstalleerde-airconditioningkanalen","property_label-nieuwbouw","property_city-aspe-nl","property_city-hondon-de-las-nieves-nl","property_city-pinoso-nl","property_area-costa-blanca-nl","property_area-costa-blanca-zuid"],"property_meta":{"_alp_processed":["1756306182"],"fave_property_price":["322000"],"fave_property_size":["142"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land":["10000+"],"fave_property_land_postfix":["m\u00b2"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_property_garage":["3+"],"fave_property_year":["2026"],"fave_property_id":["IN10-3"],"fave_property_map":["1"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_property_images":["174733","174743","174753","174763","174773","174783","174793","174803","171126","171136","171116","171146"],"fave_agent_display_option":["agent_info"],"fave_agents":["9878"],"fave_energy_class":["B"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"additional_features":["a:6:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:10:\"\ud83c\udfd6 Beach\";s:29:\"fave_additional_feature_value\";s:10:\"25 - 40 km\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:26:\"\ud83c\udf7d\ufe0f Bars & Restaurants\";s:29:\"fave_additional_feature_value\";s:8:\"2 - 5 km\";}i:2;a:2:{s:29:\"fave_additional_feature_title\";s:17:\"\ud83d\uded2 Supermarkets\";s:29:\"fave_additional_feature_value\";s:8:\"2 - 7 km\";}i:3;a:2:{s:29:\"fave_additional_feature_title\";s:14:\"\ud83c\udfe5 Hospitals\";s:29:\"fave_additional_feature_value\";s:9:\"5 - 10 km\";}i:4;a:2:{s:29:\"fave_additional_feature_title\";s:12:\"\ud83c\udf93 Schools\";s:29:\"fave_additional_feature_value\";s:9:\"5 - 10 km\";}i:5;a:2:{s:29:\"fave_additional_feature_title\";s:23:\"\u2708\ufe0f Alicante Airport\";s:29:\"fave_additional_feature_value\";s:10:\"25 - 40 km\";}}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"houzez_geolocation_lat":["38.378755597453"],"houzez_geolocation_long":["-0.90579690001881"],"_thumbnail_id":["174735"],"_last_translation_edit_mode":["translation-editor"],"_yoast_wpseo_title":["\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705"],"_yoast_wpseo_metadesc":["TE KOOP vanaf %%cf_fave_property_price%% \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | %%cf_fave_property_land%% m\u00b2 grond"],"_yoast_wpseo_focuskw":["Nieuwbouw Fincas te koop in Pinoso"],"fave_property_map_address":["El Pinoso, Aspe, La Romana, La Canalosa, Elche etc. (Alicante, Spanje)"],"fave_property_location":["38.378755597453,-0.90579690001881,10"],"fave_property_map_street_view":["verbergen"],"fave_property_address":["El Pinoso, Alicante, Spanje en anderen"],"fave_prop_homeslider":["Nee"],"floor_plans":["a:1:{i:0;a:2:{s:15:\"fave_plan_title\";s:11:\"Plattegrond\";s:15:\"fave_plan_image\";s:140:\"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-8.jpg\";}}"],"_wpml_word_count":["12"],"houzez_total_property_views":["345"],"houzez_views_by_date":["a:61:{s:10:\"04-19-2026\";i:1;s:10:\"04-23-2026\";i:1;s:10:\"04-26-2026\";i:3;s:10:\"04-27-2026\";i:1;s:10:\"04-28-2026\";i:1;s:10:\"05-03-2026\";i:3;s:10:\"05-04-2026\";i:5;s:10:\"05-05-2026\";i:2;s:10:\"05-08-2026\";i:3;s:10:\"05-10-2026\";i:2;s:10:\"05-15-2026\";i:1;s:10:\"05-17-2026\";i:1;s:10:\"05-18-2026\";i:2;s:10:\"05-21-2026\";i:2;s:10:\"05-22-2026\";i:1;s:10:\"05-24-2026\";i:2;s:10:\"05-26-2026\";i:1;s:10:\"05-28-2026\";i:1;s:10:\"05-30-2026\";i:4;s:10:\"05-31-2026\";i:1;s:10:\"06-03-2026\";i:7;s:10:\"06-07-2026\";i:3;s:10:\"06-12-2026\";i:1;s:10:\"06-13-2026\";i:2;s:10:\"06-14-2026\";i:1;s:10:\"06-19-2026\";i:3;s:10:\"06-21-2026\";i:2;s:10:\"06-22-2026\";i:1;s:10:\"06-24-2026\";i:1;s:10:\"06-28-2026\";i:1;s:10:\"06-29-2026\";i:2;s:10:\"06-30-2026\";i:1;s:10:\"07-01-2026\";i:1;s:10:\"07-02-2026\";i:1;s:10:\"07-03-2026\";i:1;s:10:\"07-05-2026\";i:2;s:10:\"07-12-2026\";i:1;s:10:\"07-15-2026\";i:4;s:10:\"07-17-2026\";i:1;s:10:\"07-19-2026\";i:1;s:10:\"07-23-2026\";i:1;s:10:\"07-26-2026\";i:1;s:10:\"07-27-2026\";i:1;s:10:\"07-28-2026\";i:2;s:10:\"07-29-2026\";i:2;s:10:\"07-30-2026\";i:1;s:10:\"08-02-2026\";i:1;s:10:\"08-08-2026\";i:1;s:10:\"08-09-2026\";i:1;s:10:\"08-11-2026\";i:4;s:10:\"08-12-2026\";i:3;s:10:\"08-16-2026\";i:1;s:10:\"08-18-2026\";i:2;s:10:\"08-19-2026\";i:3;s:10:\"08-23-2026\";i:2;s:10:\"08-27-2026\";i:1;s:10:\"08-29-2026\";i:1;s:10:\"08-30-2026\";i:1;s:10:\"08-31-2026\";i:1;s:10:\"09-01-2026\";i:1;s:10:\"09-02-2026\";i:1;}"],"houzez_recently_viewed":["2026-09-02 17:31:18"],"litespeed_vpi_list":["a:3:{i:0;s:34:\"Borislav-La-Bella-Vita-150x150.jpg\";i:1;s:27:\"La-Bella-Vita-Logo-Left.svg\";i:2;s:79:\"New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\";}"],"_elementor_global_class_usage_indexed":["1"],"_lbv_delivery_checked_v1":["1"],"_lbv_completion_sort_asc_v2":["999999"],"_lbv_completion_sort_desc_v2":["0"],"_lbv_completion_sort_state_v2":["unknown"],"_cmplz_scanned_post":["1"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705<\/title>\n<meta name=\"description\" content=\"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705\" \/>\n<meta property=\"og:description\" content=\"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BELLA VITA Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/labellavitarealestate\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T14:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond\" \/>\n<meta name=\"twitter:site\" content=\"@LBV_Real_Estate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/\"},\"author\":{\"name\":\"Diana Tsybulina\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#\\\/schema\\\/person\\\/681224c7252cd962ee224588e6c07d18\"},\"headline\":\"Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland)\",\"datePublished\":\"2025-08-27T14:33:58+00:00\",\"dateModified\":\"2025-08-27T14:49:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\",\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/\",\"name\":\"\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\",\"datePublished\":\"2025-08-27T14:33:58+00:00\",\"dateModified\":\"2025-08-27T14:49:42+00:00\",\"description\":\"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#primaryimage\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\",\"contentUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg\",\"width\":1170,\"height\":658,\"caption\":\"New Build Fincas for sale in Pinoso, Aspe and Surroundings (Alicante Inland)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eigenschappen\",\"item\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/\",\"name\":\"LA BELLA VITA Real Estate in Costa Blanca, Spain\",\"description\":\"Properties for sale in Costa Blanca\",\"publisher\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#organization\"},\"alternateName\":\"LA BELLA VITA Real Estate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#organization\",\"name\":\"LA BELLA VITA Real Estate in Costa Blanca\",\"alternateName\":\"LA BELLA VITA\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la-bella-vita-logotype-gold.svg\",\"contentUrl\":\"https:\\\/\\\/labellavitarealestate.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la-bella-vita-logotype-gold.svg\",\"width\":366,\"height\":71,\"caption\":\"LA BELLA VITA Real Estate in Costa Blanca\"},\"image\":{\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/labellavitarealestate\",\"https:\\\/\\\/x.com\\\/LBV_Real_Estate\",\"https:\\\/\\\/www.instagram.com\\\/labellavita_real_estate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/labellavitarealestate\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/labellavitarealestate\\\/_saved\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCP6t8aNDgIarJyJYgFZ4XTA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/#\\\/schema\\\/person\\\/681224c7252cd962ee224588e6c07d18\",\"name\":\"Diana Tsybulina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g\",\"caption\":\"Diana Tsybulina\"},\"url\":\"https:\\\/\\\/labellavitarealestate.com\\\/nl\\\/author\\\/diana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705","description":"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/","og_locale":"nl_NL","og_type":"article","og_title":"\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705","og_description":"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond","og_url":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/","og_site_name":"LA BELLA VITA Real Estate","article_publisher":"https:\/\/www.facebook.com\/labellavitarealestate","article_modified_time":"2025-08-27T14:49:42+00:00","og_image":[{"width":1170,"height":658,"url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond","twitter_site":"@LBV_Real_Estate","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#article","isPartOf":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/"},"author":{"name":"Diana Tsybulina","@id":"https:\/\/labellavitarealestate.com\/nl\/#\/schema\/person\/681224c7252cd962ee224588e6c07d18"},"headline":"Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland)","datePublished":"2025-08-27T14:33:58+00:00","dateModified":"2025-08-27T14:49:42+00:00","mainEntityOfPage":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/"},"wordCount":11,"publisher":{"@id":"https:\/\/labellavitarealestate.com\/nl\/#organization"},"image":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#primaryimage"},"thumbnailUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg","inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/","url":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/","name":"\u27a1\ufe0f Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving \u2705","isPartOf":{"@id":"https:\/\/labellavitarealestate.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#primaryimage"},"image":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#primaryimage"},"thumbnailUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg","datePublished":"2025-08-27T14:33:58+00:00","dateModified":"2025-08-27T14:49:42+00:00","description":"TE KOOP vanaf 322000 \u20ac Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland) | 2-3 slaapkamers | zwembad | 10000+ m\u00b2 grond","breadcrumb":{"@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#primaryimage","url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg","contentUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2025\/08\/New-Build-Fincas-for-sale-in-Pinoso-Aspe-and-Surroundings-Alicante-Inland-1.jpg","width":1170,"height":658,"caption":"New Build Fincas for sale in Pinoso, Aspe and Surroundings (Alicante Inland)"},{"@type":"BreadcrumbList","@id":"https:\/\/labellavitarealestate.com\/nl\/property\/in10-3-new-build-fincas-for-sale-in-pinoso-alicante-inland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/labellavitarealestate.com\/nl\/"},{"@type":"ListItem","position":2,"name":"eigenschappen","item":"https:\/\/labellavitarealestate.com\/nl\/property\/"},{"@type":"ListItem","position":3,"name":"Nieuwbouw Fincas te koop in Pinoso, Aspe en omgeving (Alicante Inland)"}]},{"@type":"WebSite","@id":"https:\/\/labellavitarealestate.com\/nl\/#website","url":"https:\/\/labellavitarealestate.com\/nl\/","name":"LA BELLA VITA Real Estate in Costa Blanca, Spain","description":"Properties for sale in Costa Blanca","publisher":{"@id":"https:\/\/labellavitarealestate.com\/nl\/#organization"},"alternateName":"LA BELLA VITA Real Estate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labellavitarealestate.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/labellavitarealestate.com\/nl\/#organization","name":"LA BELLA VITA Real Estate in Costa Blanca","alternateName":"LA BELLA VITA","url":"https:\/\/labellavitarealestate.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/labellavitarealestate.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2021\/12\/la-bella-vita-logotype-gold.svg","contentUrl":"https:\/\/labellavitarealestate.com\/wp-content\/uploads\/2021\/12\/la-bella-vita-logotype-gold.svg","width":366,"height":71,"caption":"LA BELLA VITA Real Estate in Costa Blanca"},"image":{"@id":"https:\/\/labellavitarealestate.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/labellavitarealestate","https:\/\/x.com\/LBV_Real_Estate","https:\/\/www.instagram.com\/labellavita_real_estate\/","https:\/\/www.linkedin.com\/in\/labellavitarealestate\/","https:\/\/www.pinterest.es\/labellavitarealestate\/_saved\/","https:\/\/www.youtube.com\/channel\/UCP6t8aNDgIarJyJYgFZ4XTA"]},{"@type":"Person","@id":"https:\/\/labellavitarealestate.com\/nl\/#\/schema\/person\/681224c7252cd962ee224588e6c07d18","name":"Diana Tsybulina","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c35f95fb70cbb502f9a829ca76f96959bc5c186600769791cd3cc437921354ea?s=96&d=mm&r=g","caption":"Diana Tsybulina"},"url":"https:\/\/labellavitarealestate.com\/nl\/author\/diana\/"}]}},"_links":{"self":[{"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/properties\/174843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/properties\/174843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/media\/174735"}],"wp:attachment":[{"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/media?parent=174843"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_type?post=174843"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_status?post=174843"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_feature?post=174843"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_label?post=174843"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_city?post=174843"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/labellavitarealestate.com\/nl\/wp-json\/wp\/v2\/property_area?post=174843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}